{"id":9161,"date":"2021-03-15T17:16:28","date_gmt":"2021-03-15T17:16:28","guid":{"rendered":"https:\/\/profesornativodealeman.com\/clases-aleman\/?p=9161"},"modified":"2021-03-15T17:16:28","modified_gmt":"2021-03-15T17:16:28","slug":"clases-aleman-con-aurea","status":"publish","type":"post","link":"https:\/\/profesornativodealeman.com\/clases-aleman\/clases-aleman-con-aurea\/","title":{"rendered":"Clases de aleman con Aurea. Opiniones de sus alumnos"},"content":{"rendered":"<p>Aurea, igual que las otras compa\u00f1eras que trabajan conmigo, es una de las mejores profesoras de alem\u00e1n que un alumno puede encontrar. Prueba de ello son las opiniones de sus alumnos:<\/p>\n<p><strong>Mar\u00eda Jos\u00e9 Labrigui Rubio (de Sevilla, ahora vive en Alemania)<img decoding=\"async\" class=\"alignright wp-image-9006\" src=\"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-content\/uploads\/2021\/02\/fotocv.jpg\" alt=\"Clases de alem\u00e1n online\" width=\"160\" height=\"160\" title=\"\"><\/strong><br \/>\n<strong>Profesion: Ingeniera<\/strong><\/p>\n<p><strong>\u00bfpor qu\u00e9 recomendar\u00edas a \u00c1urea como profesor para dar clases de alem\u00e1n ?<\/strong><\/p>\n<ul>\n<li>En mi caso he recurrido a las clases con \u00c1urea como apoyo para preparar la prueba TELC B1. Principalmente recomiendo las clases con \u00c1urea porque es una gran profesional, con experiencia y mucha entrega. Las clases est\u00e1n personalizadas para poder cumplir los objetivos que nos marcamos los alumnos. Tambi\u00e9n destacar que sabe conducir muy bien las clases y tiene una enorme paciencia.<\/li>\n<\/ul>\n<p><strong>\u00bf que te ha gustado en su m\u00e9todo?<\/strong><\/p>\n<ul>\n<li>Las clases son muy din\u00e1micas y amenas. En mi caso, el m\u00e9todo se basa en identificar las partes que hay que reforzar y trabajar mediante ejercicios orales y escritos. Para todo esto se apoya en una gran cantidad de material que est\u00e1 disponible en formato digital, por lo que es de gran ayuda para las clases on-line.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Bel\u00e9n Palazuelos Bl\u00e1zquez (Madrid)<\/strong><\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-9001 alignright\" src=\"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-content\/uploads\/2021\/01\/image-1.jpg\" alt=\"Clases de alem\u00e1n online\" width=\"150\" height=\"188\" title=\"\"><\/strong><\/p>\n<p><strong>\u00bfpor qu\u00e9 recomendar\u00edas a \u00c1urea como profesor para dar clases de alem\u00e1n ?<\/strong><\/p>\n<ul>\n<li>\u00c1urea da clases online a mi hija de 11 a\u00f1os, est\u00e1 progresando mucho, le gusta, est\u00e1 muy motivada y aprende en cada una de ellas de una manera muy did\u00e1ctica y organizada.<\/li>\n<\/ul>\n<p><strong>\u00bf que te ha gustado en su m\u00e9todo?<\/strong><\/p>\n<ul>\n<li>Mucho, se nota su profesionalidad por la manera de estructurar la clase, las tareas propuestas y su forma de ense\u00f1ar. La recomido 100%.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Aqui su perfil completo\u00a0 con el formulario de contacto:<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"KPE00Vyj2A\"><p><a href=\"https:\/\/profesornativodealeman.com\/clases-aleman\/co-examinadora-goethe\/\">Co-examinadora del instituto Goethe. Poliglota, 7 Idiomas.<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abCo-examinadora del instituto Goethe. Poliglota, 7 Idiomas.\u00bb \u2014 Profesor de alem\u00e1n online acreditado. Nativo y Coach de alem\u00e1n.\" src=\"https:\/\/profesornativodealeman.com\/clases-aleman\/co-examinadora-goethe\/embed\/#?secret=PoL3q6lgUl#?secret=KPE00Vyj2A\" data-secret=\"KPE00Vyj2A\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aurea, igual que las otras compa\u00f1eras que trabajan conmigo, es una de las mejores profesoras de alem\u00e1n que un alumno puede encontrar. Prueba de ello son las opiniones de sus alumnos: Mar\u00eda Jos\u00e9 Labrigui Rubio (de Sevilla, ahora vive en Alemania) Profesion: Ingeniera \u00bfpor qu\u00e9 recomendar\u00edas a \u00c1urea como profesor para dar clases de alem\u00e1n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3711],"tags":[],"class_list":["post-9161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clases-de-aleman"],"_links":{"self":[{"href":"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-json\/wp\/v2\/posts\/9161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-json\/wp\/v2\/comments?post=9161"}],"version-history":[{"count":0,"href":"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-json\/wp\/v2\/posts\/9161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-json\/wp\/v2\/media\/8559"}],"wp:attachment":[{"href":"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-json\/wp\/v2\/media?parent=9161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-json\/wp\/v2\/categories?post=9161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/profesornativodealeman.com\/clases-aleman\/wp-json\/wp\/v2\/tags?post=9161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}